{"id":17,"count":2,"description":"Quand nous sommes mobiles, nous avons besoin souvent d'un navigateur GPS, d'enregistrer nos parcours (surtout les sportifs) ou d'enregistrer notre conduite en voiture ou v\u00e9lo.","link":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/","name":"Mobilit\u00e9","slug":"mobilite","taxonomy":"category","parent":26,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Mobilit\u00e9 - Club Informatique Gassendi<\/title>\n<meta name=\"description\" content=\"Quand nous sommes mobiles, nous avons besoin souvent d&#039;un navigateur GPS, d&#039;enregistrer nos parcours (surtout les sportifs) ou d&#039;enregistrer notre conduite en voiture ou v\u00e9lo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Mobilit\u00e9 - Club Informatique Gassendi\" \/>\n<meta property=\"og:description\" content=\"Quand nous sommes mobiles, nous avons besoin souvent d&#039;un navigateur GPS, d&#039;enregistrer nos parcours (surtout les sportifs) ou d&#039;enregistrer notre conduite en voiture ou v\u00e9lo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Informatique Gassendi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/category\\\/le-blog-du-club\\\/mobilite\\\/\",\"url\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/category\\\/le-blog-du-club\\\/mobilite\\\/\",\"name\":\"Archives des Mobilit\u00e9 - Club Informatique Gassendi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#website\"},\"description\":\"Quand nous sommes mobiles, nous avons besoin souvent d'un navigateur GPS, d'enregistrer nos parcours (surtout les sportifs) ou d'enregistrer notre conduite en voiture ou v\u00e9lo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/category\\\/le-blog-du-club\\\/mobilite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/category\\\/le-blog-du-club\\\/mobilite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Blog du club\",\"item\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/category\\\/le-blog-du-club\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#website\",\"url\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/\",\"name\":\"Club Informatique Gassendi\",\"description\":\"L&#039;autre fa\u00e7on d&#039;apprendre l&#039;informatique ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#organization\",\"name\":\"Club Informatique Gassendi\",\"url\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-cig_165x150.jpg\",\"contentUrl\":\"http:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-cig_165x150.jpg\",\"width\":165,\"height\":150,\"caption\":\"Club Informatique Gassendi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gassendi.asso.fr\\\/wpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Mobilit\u00e9 - Club Informatique Gassendi","description":"Quand nous sommes mobiles, nous avons besoin souvent d'un navigateur GPS, d'enregistrer nos parcours (surtout les sportifs) ou d'enregistrer notre conduite en voiture ou v\u00e9lo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Mobilit\u00e9 - Club Informatique Gassendi","og_description":"Quand nous sommes mobiles, nous avons besoin souvent d'un navigateur GPS, d'enregistrer nos parcours (surtout les sportifs) ou d'enregistrer notre conduite en voiture ou v\u00e9lo.","og_url":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/","og_site_name":"Club Informatique Gassendi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/","url":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/","name":"Archives des Mobilit\u00e9 - Club Informatique Gassendi","isPartOf":{"@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#website"},"description":"Quand nous sommes mobiles, nous avons besoin souvent d'un navigateur GPS, d'enregistrer nos parcours (surtout les sportifs) ou d'enregistrer notre conduite en voiture ou v\u00e9lo.","breadcrumb":{"@id":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/mobilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gassendi.asso.fr\/wpg\/"},{"@type":"ListItem","position":2,"name":"Le Blog du club","item":"https:\/\/www.gassendi.asso.fr\/wpg\/category\/le-blog-du-club\/"},{"@type":"ListItem","position":3,"name":"Mobilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#website","url":"https:\/\/www.gassendi.asso.fr\/wpg\/","name":"Club Informatique Gassendi","description":"L&#039;autre fa\u00e7on d&#039;apprendre l&#039;informatique ...","publisher":{"@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gassendi.asso.fr\/wpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#organization","name":"Club Informatique Gassendi","url":"https:\/\/www.gassendi.asso.fr\/wpg\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#\/schema\/logo\/image\/","url":"http:\/\/www.gassendi.asso.fr\/wpg\/wp-content\/uploads\/2019\/06\/logo-cig_165x150.jpg","contentUrl":"http:\/\/www.gassendi.asso.fr\/wpg\/wp-content\/uploads\/2019\/06\/logo-cig_165x150.jpg","width":165,"height":150,"caption":"Club Informatique Gassendi"},"image":{"@id":"https:\/\/www.gassendi.asso.fr\/wpg\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.gassendi.asso.fr\/wpg\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gassendi.asso.fr\/wpg\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.gassendi.asso.fr\/wpg\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.gassendi.asso.fr\/wpg\/wp-json\/wp\/v2\/categories\/26"}],"wp:post_type":[{"href":"https:\/\/www.gassendi.asso.fr\/wpg\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}